{"id":36246,"date":"2026-05-22T17:46:04","date_gmt":"2026-05-22T15:46:04","guid":{"rendered":"https:\/\/clicasia.com\/?p=36246"},"modified":"2026-05-22T17:46:25","modified_gmt":"2026-05-22T15:46:25","slug":"clicasia-ya-acepta-pluxee-empieza-a-invertir-en-tu-aprendizaje","status":"publish","type":"post","link":"https:\/\/clicasia.com\/ca\/clicasia-ya-acepta-pluxee-empieza-a-invertir-en-tu-aprendizaje\/","title":{"rendered":"ClicAsia\u00a0ya acepta\u00a0Pluxee: empieza a invertir en tu aprendizaje"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"36246\" class=\"elementor elementor-36246\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19ec0d4 elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"19ec0d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11ec04e\" data-id=\"11ec04e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86afc1a elementor-widget elementor-widget-text-editor\" data-id=\"86afc1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">En\u00a0ClicAsia\u00a0creemos que aprender un idioma es una inversi\u00f3n en el futuro: abre puertas profesionales, conecta culturas y crea nuevas oportunidades personales. Por eso, seguimos trabajando para que acceder a nuestros cursos sea cada vez m\u00e1s sencillo y flexible.<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Nos alegra anunciar que\u00a0<\/span><b><span data-contrast=\"auto\">ClicAsia\u00a0ya acepta\u00a0Pluxee<\/span><\/b><span data-contrast=\"auto\">\u00a0como m\u00e9todo de pago.<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Gracias a esta colaboraci\u00f3n, nuestros alumnos podr\u00e1n utilizar su saldo\u00a0Pluxee\u00a0para acceder a la formaci\u00f3n y seguir avanzando en sus objetivos acad\u00e9micos y profesionales de una forma m\u00e1s c\u00f3moda.<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba3364a elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"ba3364a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d01ac3a\" data-id=\"d01ac3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f067daa elementor-widget elementor-widget-heading\" data-id=\"f067daa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 es Pluxee?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a675d0 elementor-widget elementor-widget-text-editor\" data-id=\"2a675d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW62901044 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SpellingErrorV2Themed SCXW62901044 BCX0\">Pluxee<\/span><span class=\"NormalTextRun SCXW62901044 BCX0\">\u00a0es una empresa especializada en\u00a0<\/span><\/span><span class=\"TextRun SCXW62901044 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW62901044 BCX0\">beneficios para empleados<\/span><\/span><span class=\"TextRun SCXW62901044 BCX0\" lang=\"ES-ES\" xml:lang=\"ES-ES\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW62901044 BCX0\">. Muchas compa\u00f1\u00edas ofrecen a sus trabajadores una serie de ventajas adicionales al salario \u2014como ayudas para comida, transporte, formaci\u00f3n o bienestar\u2014 y\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW62901044 BCX0\">Pluxee<\/span><span class=\"NormalTextRun SCXW62901044 BCX0\">\u00a0es la plataforma que permite gestionar y utilizar esos beneficios de forma sencilla.<\/span><\/span><span class=\"EOP SCXW62901044 BCX0\" data-ccp-props=\"{&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-534e03c elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"534e03c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71c2e8d\" data-id=\"71c2e8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a002ea6 elementor-widget elementor-widget-image\" data-id=\"a002ea6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/cdg_case-study_pluxee-assets_015-1376x774-1-1024x576.webp\" class=\"attachment-large size-large wp-image-36248\" alt=\"\" srcset=\"https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/cdg_case-study_pluxee-assets_015-1376x774-1-1024x576.webp 1024w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/cdg_case-study_pluxee-assets_015-1376x774-1-300x169.webp 300w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/cdg_case-study_pluxee-assets_015-1376x774-1-768x432.webp 768w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/cdg_case-study_pluxee-assets_015-1376x774-1-400x225.webp 400w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/cdg_case-study_pluxee-assets_015-1376x774-1-600x338.webp 600w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/cdg_case-study_pluxee-assets_015-1376x774-1.webp 1376w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ac775a elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"1ac775a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e2b3afe\" data-id=\"e2b3afe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-333d972 elementor-widget elementor-widget-text-editor\" data-id=\"333d972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">A trav\u00e9s de una tarjeta o aplicaci\u00f3n, los usuarios pueden acceder al saldo que su empresa pone a su disposici\u00f3n y utilizarlo en establecimientos y servicios adheridos.<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Uno de esos beneficios puede estar destinado al\u00a0<\/span><b><span data-contrast=\"auto\">desarrollo profesional y la formaci\u00f3n<\/span><\/b><span data-contrast=\"auto\">, permitiendo invertir en cursos y aprendizaje.<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Y ahora, gracias a nuestra colaboraci\u00f3n,\u00a0<\/span><b><span data-contrast=\"auto\">ese saldo tambi\u00e9n puede utilizarse en\u00a0ClicAsia<\/span><\/b><span data-contrast=\"auto\">\u00a0para estudiar idiomas.<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cff3fe2 elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"cff3fe2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3f11b1\" data-id=\"a3f11b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2192fea elementor-widget elementor-widget-heading\" data-id=\"2192fea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo funciona el pago con Pluxee en ClicAsia? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aef80f3 elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"aef80f3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11410c2\" data-id=\"11410c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b478b0f elementor-widget elementor-widget-text-editor\" data-id=\"b478b0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Utilizar\u00a0Pluxee\u00a0en\u00a0ClicAsia\u00a0es muy sencillo:<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><ol><li aria-setsize=\"-1\" data-leveltext=\"%1.\" data-font=\"\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:0,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[65533,0],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;%1.&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Elige el curso que quieras realizar.<\/span><span data-ccp-props=\"{&quot;134233118&quot;:false,&quot;335559685&quot;:720,&quot;335559738&quot;:240,&quot;335559739&quot;:0,&quot;335559991&quot;:360}\">\u00a0<\/span><\/li><li aria-setsize=\"-1\" data-leveltext=\"%1.\" data-font=\"\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:0,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[65533,0],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;%1.&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Indica durante el proceso de inscripci\u00f3n que deseas utilizar\u00a0Pluxee\u00a0como forma de pago.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559685&quot;:720,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559991&quot;:360}\">\u00a0<\/span><\/li><li aria-setsize=\"-1\" data-leveltext=\"%1.\" data-font=\"\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:0,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769242&quot;:[65533,0],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;%1.&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Nuestro equipo te ayudar\u00e1 a gestionar el proceso y confirmar la aplicaci\u00f3n del pago seg\u00fan el tipo de beneficio disponible.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;335559685&quot;:720,&quot;335559738&quot;:0,&quot;335559739&quot;:240,&quot;335559991&quot;:360}\">\u00a0<\/span><\/li><\/ol><p><span data-contrast=\"auto\">Si tienes cualquier duda antes de completar la inscripci\u00f3n, estaremos encantados de ayudarte.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-027aa25 elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"027aa25\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fb465e4\" data-id=\"fb465e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d25ebb4 elementor-widget elementor-widget-heading\" data-id=\"d25ebb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Una colaboraci\u00f3n que impulsa el aprendizaje <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-535e84f elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"535e84f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ebac68\" data-id=\"9ebac68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-834397e elementor-widget elementor-widget-text-editor\" data-id=\"834397e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Esta colaboraci\u00f3n con\u00a0Pluxee\u00a0representa un paso m\u00e1s en nuestro compromiso por hacer que el aprendizaje de idiomas sea m\u00e1s accesible y adaptable a cada alumno.<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">En\u00a0ClicAsia\u00a0creemos que aprender un idioma no solo significa asistir a clase: significa descubrir nuevas culturas, ampliar horizontes y crear oportunidades para el futuro.<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Ahora, gracias a\u00a0Pluxee, queremos que ese camino sea todav\u00eda m\u00e1s f\u00e1cil.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-292111a elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"292111a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-452587e\" data-id=\"452587e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caa00ce elementor-widget elementor-widget-heading\" data-id=\"caa00ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Empieza tu pr\u00f3ximo idioma con ClicAsia <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f26a9eb elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"f26a9eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-328dd67\" data-id=\"328dd67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a3683a elementor-widget elementor-widget-image\" data-id=\"5a3683a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"334\" src=\"https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_Thailand.svg.png\" class=\"attachment-large size-large wp-image-36252\" alt=\"\" srcset=\"https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_Thailand.svg.png 500w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_Thailand.svg-300x200.png 300w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_Thailand.svg-400x267.png 400w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-34224a1\" data-id=\"34224a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84cf710 elementor-widget elementor-widget-image\" data-id=\"84cf710\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"334\" src=\"https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_South_Korea.svg.png\" class=\"attachment-large size-large wp-image-36253\" alt=\"\" srcset=\"https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_South_Korea.svg.png 500w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_South_Korea.svg-300x200.png 300w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_South_Korea.svg-400x267.png 400w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-147b2af\" data-id=\"147b2af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a34999 elementor-widget elementor-widget-image\" data-id=\"3a34999\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"334\" src=\"https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_the_Peoples_Republic_of_China.svg.png\" class=\"attachment-large size-large wp-image-36255\" alt=\"\" srcset=\"https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_the_Peoples_Republic_of_China.svg.png 500w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_the_Peoples_Republic_of_China.svg-300x200.png 300w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_the_Peoples_Republic_of_China.svg-400x267.png 400w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c6412dc\" data-id=\"c6412dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d1333d elementor-widget elementor-widget-image\" data-id=\"6d1333d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"334\" src=\"https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_Japan.svg.png\" class=\"attachment-large size-large wp-image-36254\" alt=\"\" srcset=\"https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_Japan.svg.png 500w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_Japan.svg-300x200.png 300w, https:\/\/clicasia.com\/wp-content\/uploads\/2026\/05\/Flag_of_Japan.svg-400x267.png 400w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74c4274 elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"74c4274\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-caacc1f\" data-id=\"caacc1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0261c23 elementor-widget elementor-widget-text-editor\" data-id=\"0261c23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Ya sea que quieras aprender japon\u00e9s, coreano, chino, tailand\u00e9s o cualquiera de los idiomas que ofrecemos, ahora tienes una nueva manera de comenzar.<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Tu formaci\u00f3n ya puede formar parte de tus beneficios. Y nosotros estaremos encantados de acompa\u00f1arte en ese proceso. <\/span><\/b>Si quieres aprender idiomas con nosotros rellena el formulario de contacto y te daremos la informaci\u00f3n que necesitas:<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea24cdf elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"ea24cdf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c937ec9\" data-id=\"c937ec9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1118f6 edumall-contact-form-style-01 edumall-button-align-stretch elementor-widget elementor-widget-tm-contact-form-7\" data-id=\"b1118f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tm-contact-form-7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"edumall-contact-form-7\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f34770-o1\" lang=\"ca\" dir=\"ltr\" data-wpcf7-id=\"34770\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ca\/wp-json\/wp\/v2\/posts\/36246#wpcf7-f34770-o1\" method=\"post\" class=\"wpcf7-form init e03e3b1aa08b cmatic-conn cmatic-aud-3 cmatic-mapd0-0 cmatic-098109 cmatic-sent-0 cmatic-total-3745\" aria-label=\"Formulari de contacte\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"34770\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ca\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f34770-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-md-12\">\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"form-input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"El teu email\" value=\"\" type=\"email\" name=\"Email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-6\">\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"form-input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control form-input\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"El teu nom\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-md-6\">\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"form-input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Idioma\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"Idioma\"><option value=\"Tria un idioma\">Tria un idioma<\/option><option value=\"Xin\u00e8s\">Xin\u00e8s<\/option><option value=\"Core\u00e0\">Core\u00e0<\/option><option value=\"Japon\u00e8s\">Japon\u00e8s<\/option><option value=\"Turc\">Turc<\/option><option value=\"Tailand\u00e8s\">Tailand\u00e8s<\/option><option value=\"\u00c0rab\">\u00c0rab<\/option><option value=\"Rus\">Rus<\/option><option value=\"Hindi\">Hindi<\/option><option value=\"Urdu\">Urdu<\/option><option value=\"Farsi\">Farsi<\/option><option value=\"Vietnamita\">Vietnamita<\/option><option value=\"Mongol\">Mongol<\/option><option value=\"Indon\u00e8si\">Indon\u00e8si<\/option><option value=\"Tagalog\">Tagalog<\/option><option value=\"Panjabi (\u00cdndia)\">Panjabi (\u00cdndia)<\/option><option value=\"Panjabi (Pakistan)\">Panjabi (Pakistan)<\/option><option value=\"Canton\u00e8s\">Canton\u00e8s<\/option><option value=\"Tayiko\">Tayiko<\/option><option value=\"Azerbaidjan\">Azerbaidjan<\/option><option value=\"Altres\">Altres<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-6\">\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"form-input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Telfono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"El teu tel\u00e8fon\" value=\"\" type=\"tel\" name=\"Telfono\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-md-6\" style=\"margin-bottom:5px;\">\n\t\t<div class=\"form-input-group\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Nivel\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"Nivel\"><option value=\"Tria el teu nivell\">Tria el teu nivell<\/option><option value=\"Zero\">Zero<\/option><option value=\"B\u00e0sic\">B\u00e0sic<\/option><option value=\"Intermedi\">Intermedi<\/option><option value=\"Avan\u00e7at\">Avan\u00e7at<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-6\">\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"form-input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Horario\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"Horario\"><option value=\"Tria un horari\">Tria un horari<\/option><option value=\"Mat\u00ed\">Mat\u00ed<\/option><option value=\"Tarda\">Tarda<\/option><option value=\"Indiferent\">Indiferent<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-md-6\">\n\t\t<div class=\"form-group\">\n\t\t\t<div class=\"form-input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Ciudad\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"Ciudad\"><option value=\"Tria una ciutat\">Tria una ciutat<\/option><option value=\"Barcelona\">Barcelona<\/option><option value=\"Madrid\">Madrid<\/option><option value=\"Online\">Online<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-12\">\n\t\t<div class=\"form-input-group\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Tumensaje\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"El teu missatge\" value=\"\" type=\"text\" name=\"Tumensaje\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div style=\"display:none;\">\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Aceptacion\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"Aceptacion\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He llegit i accepto <a href=\"https:\/\/clicasia.com\/mensaje-contacto\/\">l'Av\u00eds Legal i la Pol\u00edtica de Privadesa<\/a><\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<div class=\"form-submit\">\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envia\" \/>\n\t<\/p>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"115\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En\u00a0ClicAsia\u00a0creemos que aprender un idioma es una inversi\u00f3n en el futuro: abre puertas profesionales, conecta culturas y crea nuevas oportunidades personales. Por eso, seguimos trabajando para que acceder a nuestros cursos sea cada vez m\u00e1s sencillo y flexible.\u00a0 Nos alegra anunciar que\u00a0ClicAsia\u00a0ya acepta\u00a0Pluxee\u00a0como m\u00e9todo de pago.\u00a0 Gracias a esta colaboraci\u00f3n, nuestros alumnos podr\u00e1n utilizar su saldo\u00a0Pluxee\u00a0para acceder a la formaci\u00f3n y seguir avanzando en sus objetivos acad\u00e9micos y profesionales de una forma m\u00e1s c\u00f3moda.\u00a0 \u00bfQu\u00e9 es Pluxee? Pluxee\u00a0es una empresa especializada en\u00a0beneficios para empleados. Muchas compa\u00f1\u00edas ofrecen a sus trabajadores una serie de ventajas adicionales al salario \u2014como ayudas para comida, transporte, formaci\u00f3n o bienestar\u2014 y\u00a0Pluxee\u00a0es la plataforma que permite gestionar y utilizar esos beneficios de forma sencilla.\u00a0 A trav\u00e9s de una tarjeta o aplicaci\u00f3n, los usuarios pueden acceder al saldo que su empresa pone a su disposici\u00f3n y utilizarlo en establecimientos y servicios adheridos.\u00a0 Uno de esos beneficios puede estar destinado al\u00a0desarrollo profesional y la formaci\u00f3n, permitiendo invertir en cursos y aprendizaje.\u00a0 Y ahora, gracias a nuestra colaboraci\u00f3n,\u00a0ese saldo tambi\u00e9n puede utilizarse en\u00a0ClicAsia\u00a0para estudiar idiomas.\u00a0 \u00bfC\u00f3mo funciona el pago con Pluxee en ClicAsia? Utilizar\u00a0Pluxee\u00a0en\u00a0ClicAsia\u00a0es muy sencillo:\u00a0 Elige el curso que quieras realizar.\u00a0 Indica durante el proceso de inscripci\u00f3n que deseas utilizar\u00a0Pluxee\u00a0como forma de pago.\u00a0 Nuestro equipo te ayudar\u00e1 a gestionar el proceso y confirmar la aplicaci\u00f3n del pago seg\u00fan el tipo de beneficio disponible.\u00a0 Si tienes cualquier duda antes de completar la inscripci\u00f3n, estaremos encantados de ayudarte. Una colaboraci\u00f3n que impulsa el aprendizaje Esta colaboraci\u00f3n con\u00a0Pluxee\u00a0representa un paso m\u00e1s en nuestro compromiso por hacer que el aprendizaje de idiomas sea m\u00e1s accesible y adaptable a cada alumno.\u00a0 En\u00a0ClicAsia\u00a0creemos que aprender un idioma no solo significa asistir a clase: significa descubrir nuevas culturas, ampliar horizontes y crear oportunidades para el futuro.\u00a0 Ahora, gracias a\u00a0Pluxee, queremos que ese camino sea todav\u00eda m\u00e1s f\u00e1cil. Empieza tu pr\u00f3ximo idioma con ClicAsia Ya sea que quieras aprender japon\u00e9s, coreano, chino, tailand\u00e9s o cualquiera de los idiomas que ofrecemos, ahora tienes una nueva manera de comenzar.\u00a0 Tu formaci\u00f3n ya puede formar parte de tus beneficios. Y nosotros estaremos encantados de acompa\u00f1arte en ese proceso. Si quieres aprender idiomas con nosotros rellena el formulario de contacto y te daremos la informaci\u00f3n que necesitas: &#8212;Please choose an option&#8212;ChinoCoreanoJapon\u00e9sTurcoTailand\u00e9s\u00c1rabeRusoHindiUrduFarsiVietnamitaMongolIndonesioTagalogPunjabi (India)Punjabi (Pakist\u00e1n)Canton\u00e9sTayikoAzerbaiyanoOtros &#8212;Please choose an option&#8212;CeroB\u00e1sicoIntermedioAvanzado &#8212;Please choose an option&#8212;Ma\u00f1anaTardeIndiferente &#8212;Please choose an option&#8212;BarcelonaMadridOnline He le\u00eddo y acepto el Aviso Legal y la Pol\u00edtica de Privacidad &#916;<\/p>\n","protected":false},"author":4,"featured_media":36269,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"yes","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_joinchat":[],"footnotes":""},"categories":[2450,1,3122,2075],"tags":[33,497,136,147,2155,3167],"class_list":["post-36246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-clicasia","category-sin-categorizar","category-guia","category-video-tips","tag-chino","tag-clicasia","tag-coreano-2","tag-idiomas","tag-japones","tag-pluxee"],"_links":{"self":[{"href":"https:\/\/clicasia.com\/ca\/wp-json\/wp\/v2\/posts\/36246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clicasia.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clicasia.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clicasia.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/clicasia.com\/ca\/wp-json\/wp\/v2\/comments?post=36246"}],"version-history":[{"count":9,"href":"https:\/\/clicasia.com\/ca\/wp-json\/wp\/v2\/posts\/36246\/revisions"}],"predecessor-version":[{"id":36270,"href":"https:\/\/clicasia.com\/ca\/wp-json\/wp\/v2\/posts\/36246\/revisions\/36270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clicasia.com\/ca\/wp-json\/wp\/v2\/media\/36269"}],"wp:attachment":[{"href":"https:\/\/clicasia.com\/ca\/wp-json\/wp\/v2\/media?parent=36246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clicasia.com\/ca\/wp-json\/wp\/v2\/categories?post=36246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clicasia.com\/ca\/wp-json\/wp\/v2\/tags?post=36246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}